{"id":5171,"date":"2024-11-07T17:02:21","date_gmt":"2024-11-07T08:02:21","guid":{"rendered":"https:\/\/dealer.renault.jp\/renault_kobe\/?p=5171"},"modified":"2024-11-07T17:02:21","modified_gmt":"2024-11-07T08:02:21","slug":"kangoo-%e9%99%90%e5%ae%9a%e8%bb%8a-%ef%bd%a2%e3%82%af%e3%83%ab%e3%83%bc%e3%83%ab%ef%bd%a3%e3%83%87%e3%82%a3%e3%83%bc%e3%82%bc%e3%83%ab%ef%bc%ad%ef%bc%b4%e6%8a%bd%e9%81%b8%e7%94%b3%e8%be%bc%e7%b7%a0","status":"publish","type":"post","link":"https:\/\/dealer.renault.jp\/renault_kobe\/info\/kangoo-%e9%99%90%e5%ae%9a%e8%bb%8a-%ef%bd%a2%e3%82%af%e3%83%ab%e3%83%bc%e3%83%ab%ef%bd%a3%e3%83%87%e3%82%a3%e3%83%bc%e3%82%bc%e3%83%ab%ef%bc%ad%ef%bc%b4%e6%8a%bd%e9%81%b8%e7%94%b3%e8%be%bc%e7%b7%a0","title":{"rendered":"KANGOO \u9650\u5b9a\u8eca \uff62\u30af\u30eb\u30fc\u30eb\uff63\u30c7\u30a3\u30fc\u30bc\u30eb\uff2d\uff34\u62bd\u9078\u7533\u8fbc\u7de0\u5207\u8feb\u308b\u203c"},"content":{"rendered":"\n<figure class=\"wp-block-gallery columns-1 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"400\" src=\"https:\/\/dealer.renault.jp\/renault_kobe\/wp-content\/uploads\/sites\/54\/2024\/11\/top_slide_128000-1024x400.jpg\" alt=\"\" data-id=\"5172\" data-full-url=\"https:\/\/dealer.renault.jp\/renault_kobe\/wp-content\/uploads\/sites\/54\/2024\/11\/top_slide_128000.jpg\" data-link=\"https:\/\/dealer.renault.jp\/renault_kobe\/?attachment_id=5172\" class=\"wp-image-5172\" srcset=\"https:\/\/dealer.renault.jp\/renault_kobe\/wp-content\/uploads\/sites\/54\/2024\/11\/top_slide_128000-1024x400.jpg 1024w, https:\/\/dealer.renault.jp\/renault_kobe\/wp-content\/uploads\/sites\/54\/2024\/11\/top_slide_128000-300x117.jpg 300w, https:\/\/dealer.renault.jp\/renault_kobe\/wp-content\/uploads\/sites\/54\/2024\/11\/top_slide_128000-768x300.jpg 768w, https:\/\/dealer.renault.jp\/renault_kobe\/wp-content\/uploads\/sites\/54\/2024\/11\/top_slide_128000.jpg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"blocks-gallery-item__caption\"><strong>KANGOO \u9650\u5b9a\u8eca \uff62\u30af\u30eb\u30fc\u30eb\uff63\u30c7\u30a3\u30fc\u30bc\u30eb\uff2d\uff34\u767a\u8868\u30fb\u62bd\u9078\u7533\u8fbc\u958b\u59cb<\/strong><\/figcaption><\/figure><\/li><\/ul><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>10\u670827\u65e5\u3088\u308a\u62bd\u9078\u7533\u8fbc\u307f\u3092\u958b\u59cb\u3057\u3066\u304a\u308a\u307e\u3059\u300cKANGOO \u9650\u5b9a\u8eca \u30af\u30eb\u30fc\u30ebMT\u300d\u306e\u7533\u8fbc\u7de0\u5207\u304c11\u67089\u65e5\u3068\u8feb\u3063\u3066\u307e\u3044\u308a\u307e\u3057\u305f\u3002\u30c7\u30a3\u30fc\u30bc\u30ebMT\u3068\u8a00\u3046\u3053\u3068\u3082\u3042\u308a\u3054\u5fdc\u52df\u304c\u6bba\u5230\u3057\u3066\u304a\u308a\u307e\u3059\u203c\u307e\u3060\u9593\u306b\u5408\u3044\u307e\u3059\u203c\u662f\u975e\u3053\u306e\u6a5f\u4f1a\u306b\u3054\u691c\u8a0e\u304f\u3060\u3055\u3044\u203c<\/strong><\/h2>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>\u3055\u3089\u306b\u4eca\u306a\u3089\u203c<\/strong><\/h2>\n\n\n\n<figure class=\"wp-block-gallery columns-1 is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"80\" src=\"https:\/\/dealer.renault.jp\/renault_kobe\/wp-content\/uploads\/sites\/54\/2024\/11\/02_midashi01.jpg\" alt=\"\" data-id=\"5176\" data-full-url=\"https:\/\/dealer.renault.jp\/renault_kobe\/wp-content\/uploads\/sites\/54\/2024\/11\/02_midashi01.jpg\" data-link=\"https:\/\/dealer.renault.jp\/renault_kobe\/?attachment_id=5176\" class=\"wp-image-5176\" srcset=\"https:\/\/dealer.renault.jp\/renault_kobe\/wp-content\/uploads\/sites\/54\/2024\/11\/02_midashi01.jpg 1024w, https:\/\/dealer.renault.jp\/renault_kobe\/wp-content\/uploads\/sites\/54\/2024\/11\/02_midashi01-300x23.jpg 300w, https:\/\/dealer.renault.jp\/renault_kobe\/wp-content\/uploads\/sites\/54\/2024\/11\/02_midashi01-768x60.jpg 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><\/ul><\/figure>\n\n\n\n<figure class=\"wp-block-gallery columns-1 is-cropped wp-block-gallery-3 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"580\" src=\"https:\/\/dealer.renault.jp\/renault_kobe\/wp-content\/uploads\/sites\/54\/2024\/11\/01_main03.jpg\" alt=\"\" data-id=\"5175\" data-full-url=\"https:\/\/dealer.renault.jp\/renault_kobe\/wp-content\/uploads\/sites\/54\/2024\/11\/01_main03.jpg\" data-link=\"https:\/\/dealer.renault.jp\/renault_kobe\/?attachment_id=5175\" class=\"wp-image-5175\" srcset=\"https:\/\/dealer.renault.jp\/renault_kobe\/wp-content\/uploads\/sites\/54\/2024\/11\/01_main03.jpg 1024w, https:\/\/dealer.renault.jp\/renault_kobe\/wp-content\/uploads\/sites\/54\/2024\/11\/01_main03-300x170.jpg 300w, https:\/\/dealer.renault.jp\/renault_kobe\/wp-content\/uploads\/sites\/54\/2024\/11\/01_main03-768x435.jpg 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><\/ul><\/figure>\n\n\n\n<figure class=\"wp-block-gallery columns-1 is-cropped wp-block-gallery-4 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"240\" src=\"https:\/\/dealer.renault.jp\/renault_kobe\/wp-content\/uploads\/sites\/54\/2024\/11\/04_kngspo.jpg\" alt=\"\" data-id=\"5177\" data-full-url=\"https:\/\/dealer.renault.jp\/renault_kobe\/wp-content\/uploads\/sites\/54\/2024\/11\/04_kngspo.jpg\" data-link=\"https:\/\/dealer.renault.jp\/renault_kobe\/?attachment_id=5177\" class=\"wp-image-5177\" srcset=\"https:\/\/dealer.renault.jp\/renault_kobe\/wp-content\/uploads\/sites\/54\/2024\/11\/04_kngspo.jpg 1024w, https:\/\/dealer.renault.jp\/renault_kobe\/wp-content\/uploads\/sites\/54\/2024\/11\/04_kngspo-300x70.jpg 300w, https:\/\/dealer.renault.jp\/renault_kobe\/wp-content\/uploads\/sites\/54\/2024\/11\/04_kngspo-768x180.jpg 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><\/ul><\/figure>\n\n\n\n<figure class=\"wp-block-gallery columns-2 is-cropped wp-block-gallery-5 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"1024\" src=\"https:\/\/dealer.renault.jp\/renault_kobe\/wp-content\/uploads\/sites\/54\/2024\/11\/04_kng01-960x1024.jpg\" alt=\"\" data-id=\"5178\" data-link=\"https:\/\/dealer.renault.jp\/renault_kobe\/?attachment_id=5178\" class=\"wp-image-5178\" srcset=\"https:\/\/dealer.renault.jp\/renault_kobe\/wp-content\/uploads\/sites\/54\/2024\/11\/04_kng01-960x1024.jpg 960w, https:\/\/dealer.renault.jp\/renault_kobe\/wp-content\/uploads\/sites\/54\/2024\/11\/04_kng01-281x300.jpg 281w, https:\/\/dealer.renault.jp\/renault_kobe\/wp-content\/uploads\/sites\/54\/2024\/11\/04_kng01-768x819.jpg 768w, https:\/\/dealer.renault.jp\/renault_kobe\/wp-content\/uploads\/sites\/54\/2024\/11\/04_kng01.jpg 1125w\" sizes=\"auto, (max-width: 960px) 100vw, 960px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"1024\" src=\"https:\/\/dealer.renault.jp\/renault_kobe\/wp-content\/uploads\/sites\/54\/2024\/11\/04_img03-960x1024.jpg\" alt=\"\" data-id=\"5179\" data-full-url=\"https:\/\/dealer.renault.jp\/renault_kobe\/wp-content\/uploads\/sites\/54\/2024\/11\/04_img03.jpg\" data-link=\"https:\/\/dealer.renault.jp\/renault_kobe\/?attachment_id=5179\" class=\"wp-image-5179\" srcset=\"https:\/\/dealer.renault.jp\/renault_kobe\/wp-content\/uploads\/sites\/54\/2024\/11\/04_img03-960x1024.jpg 960w, https:\/\/dealer.renault.jp\/renault_kobe\/wp-content\/uploads\/sites\/54\/2024\/11\/04_img03-281x300.jpg 281w, https:\/\/dealer.renault.jp\/renault_kobe\/wp-content\/uploads\/sites\/54\/2024\/11\/04_img03-768x819.jpg 768w, https:\/\/dealer.renault.jp\/renault_kobe\/wp-content\/uploads\/sites\/54\/2024\/11\/04_img03.jpg 1125w\" sizes=\"auto, (max-width: 960px) 100vw, 960px\" \/><\/figure><\/li><\/ul><\/figure>\n\n\n\n<figure class=\"wp-block-gallery columns-1 is-cropped wp-block-gallery-6 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"200\" src=\"https:\/\/dealer.renault.jp\/renault_kobe\/wp-content\/uploads\/sites\/54\/2024\/11\/04_kngspo_o.jpg\" alt=\"\" data-id=\"5181\" data-full-url=\"https:\/\/dealer.renault.jp\/renault_kobe\/wp-content\/uploads\/sites\/54\/2024\/11\/04_kngspo_o.jpg\" data-link=\"https:\/\/dealer.renault.jp\/renault_kobe\/?attachment_id=5181\" class=\"wp-image-5181\" srcset=\"https:\/\/dealer.renault.jp\/renault_kobe\/wp-content\/uploads\/sites\/54\/2024\/11\/04_kngspo_o.jpg 1024w, https:\/\/dealer.renault.jp\/renault_kobe\/wp-content\/uploads\/sites\/54\/2024\/11\/04_kngspo_o-300x59.jpg 300w, https:\/\/dealer.renault.jp\/renault_kobe\/wp-content\/uploads\/sites\/54\/2024\/11\/04_kngspo_o-768x150.jpg 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><\/ul><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>\u3055\u3089\u306b\u30a2\u30eb\u30ab\u30ca\u306b\u306f<\/strong><\/h2>\n\n\n\n<figure class=\"wp-block-gallery columns-1 is-cropped wp-block-gallery-7 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"660\" src=\"https:\/\/dealer.renault.jp\/renault_kobe\/wp-content\/uploads\/sites\/54\/2024\/11\/01_main06.jpg\" alt=\"\" data-id=\"5183\" data-full-url=\"https:\/\/dealer.renault.jp\/renault_kobe\/wp-content\/uploads\/sites\/54\/2024\/11\/01_main06.jpg\" data-link=\"https:\/\/dealer.renault.jp\/renault_kobe\/?attachment_id=5183\" class=\"wp-image-5183\" srcset=\"https:\/\/dealer.renault.jp\/renault_kobe\/wp-content\/uploads\/sites\/54\/2024\/11\/01_main06.jpg 1024w, https:\/\/dealer.renault.jp\/renault_kobe\/wp-content\/uploads\/sites\/54\/2024\/11\/01_main06-300x193.jpg 300w, https:\/\/dealer.renault.jp\/renault_kobe\/wp-content\/uploads\/sites\/54\/2024\/11\/01_main06-768x495.jpg 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><\/ul><\/figure>\n\n\n\n<figure class=\"wp-block-gallery columns-1 is-cropped wp-block-gallery-8 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"320\" src=\"https:\/\/dealer.renault.jp\/renault_kobe\/wp-content\/uploads\/sites\/54\/2024\/11\/05_midashi04-1.jpg\" alt=\"\" data-id=\"5186\" data-full-url=\"https:\/\/dealer.renault.jp\/renault_kobe\/wp-content\/uploads\/sites\/54\/2024\/11\/05_midashi04-1.jpg\" data-link=\"https:\/\/dealer.renault.jp\/renault_kobe\/?attachment_id=5186\" class=\"wp-image-5186\" srcset=\"https:\/\/dealer.renault.jp\/renault_kobe\/wp-content\/uploads\/sites\/54\/2024\/11\/05_midashi04-1.jpg 1024w, https:\/\/dealer.renault.jp\/renault_kobe\/wp-content\/uploads\/sites\/54\/2024\/11\/05_midashi04-1-300x94.jpg 300w, https:\/\/dealer.renault.jp\/renault_kobe\/wp-content\/uploads\/sites\/54\/2024\/11\/05_midashi04-1-768x240.jpg 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><\/ul><\/figure>\n\n\n\n<figure class=\"wp-block-gallery columns-2 is-cropped wp-block-gallery-9 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"900\" src=\"https:\/\/dealer.renault.jp\/renault_kobe\/wp-content\/uploads\/sites\/54\/2024\/11\/02_img1_03.jpg\" alt=\"\" data-id=\"5184\" data-link=\"https:\/\/dealer.renault.jp\/renault_kobe\/?attachment_id=5184\" class=\"wp-image-5184\" srcset=\"https:\/\/dealer.renault.jp\/renault_kobe\/wp-content\/uploads\/sites\/54\/2024\/11\/02_img1_03.jpg 750w, https:\/\/dealer.renault.jp\/renault_kobe\/wp-content\/uploads\/sites\/54\/2024\/11\/02_img1_03-250x300.jpg 250w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"900\" src=\"https:\/\/dealer.renault.jp\/renault_kobe\/wp-content\/uploads\/sites\/54\/2024\/11\/02_img3_03.jpg\" alt=\"\" data-id=\"5185\" data-full-url=\"https:\/\/dealer.renault.jp\/renault_kobe\/wp-content\/uploads\/sites\/54\/2024\/11\/02_img3_03.jpg\" data-link=\"https:\/\/dealer.renault.jp\/renault_kobe\/?attachment_id=5185\" class=\"wp-image-5185\" srcset=\"https:\/\/dealer.renault.jp\/renault_kobe\/wp-content\/uploads\/sites\/54\/2024\/11\/02_img3_03.jpg 750w, https:\/\/dealer.renault.jp\/renault_kobe\/wp-content\/uploads\/sites\/54\/2024\/11\/02_img3_03-250x300.jpg 250w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/figure><\/li><\/ul><\/figure>\n\n\n\n<figure class=\"wp-block-gallery columns-1 is-cropped wp-block-gallery-10 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"270\" src=\"https:\/\/dealer.renault.jp\/renault_kobe\/wp-content\/uploads\/sites\/54\/2024\/11\/04_osp06-1.jpg\" alt=\"\" data-id=\"5187\" data-full-url=\"https:\/\/dealer.renault.jp\/renault_kobe\/wp-content\/uploads\/sites\/54\/2024\/11\/04_osp06-1.jpg\" data-link=\"https:\/\/dealer.renault.jp\/renault_kobe\/?attachment_id=5187\" class=\"wp-image-5187\" srcset=\"https:\/\/dealer.renault.jp\/renault_kobe\/wp-content\/uploads\/sites\/54\/2024\/11\/04_osp06-1.jpg 750w, https:\/\/dealer.renault.jp\/renault_kobe\/wp-content\/uploads\/sites\/54\/2024\/11\/04_osp06-1-300x108.jpg 300w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/figure><\/li><\/ul><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"has-inline-color has-luminous-vivid-orange-color\">\u3055\u3089\u306b\u4eca\u306a\u3089\u3001<\/span><\/h2>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"has-inline-color has-luminous-vivid-orange-color\">\uff2d\uff23\u524d\u306e\u30e2\u30c7\u30eb\u3082\u53f0\u6570\u9650\u5b9a\u3067\u3054\u6848\u5185\u53ef\u80fd\u3067\u3059\uff01<\/span><\/h2>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"has-inline-color has-luminous-vivid-orange-color\">\u58f2\u5207\u308c\u306e\u969b\u306f\u3054\u5bb9\u8d66\u304f\u3060\u3055\u3044\uff01<\/span><\/h2>\n\n\n\n<p><strong>\u30a2\u30f3\u30c8\u30e9\u30af\u30c8<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-gallery columns-2 is-cropped wp-block-gallery-11 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"434\" src=\"https:\/\/dealer.renault.jp\/renault_kobe\/wp-content\/uploads\/sites\/54\/2024\/11\/colour_03_pc.jpg\" alt=\"\" data-id=\"5188\" data-link=\"https:\/\/dealer.renault.jp\/renault_kobe\/?attachment_id=5188\" class=\"wp-image-5188\" srcset=\"https:\/\/dealer.renault.jp\/renault_kobe\/wp-content\/uploads\/sites\/54\/2024\/11\/colour_03_pc.jpg 1024w, https:\/\/dealer.renault.jp\/renault_kobe\/wp-content\/uploads\/sites\/54\/2024\/11\/colour_03_pc-300x127.jpg 300w, https:\/\/dealer.renault.jp\/renault_kobe\/wp-content\/uploads\/sites\/54\/2024\/11\/colour_03_pc-768x326.jpg 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"blocks-gallery-item__caption\"><strong>\u9650\u5b9a\u30001\u53f0<\/strong><\/figcaption><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"434\" src=\"https:\/\/dealer.renault.jp\/renault_kobe\/wp-content\/uploads\/sites\/54\/2024\/11\/colour_04_pc.jpg\" alt=\"\" data-id=\"5189\" data-full-url=\"https:\/\/dealer.renault.jp\/renault_kobe\/wp-content\/uploads\/sites\/54\/2024\/11\/colour_04_pc.jpg\" data-link=\"https:\/\/dealer.renault.jp\/renault_kobe\/?attachment_id=5189\" class=\"wp-image-5189\" srcset=\"https:\/\/dealer.renault.jp\/renault_kobe\/wp-content\/uploads\/sites\/54\/2024\/11\/colour_04_pc.jpg 1024w, https:\/\/dealer.renault.jp\/renault_kobe\/wp-content\/uploads\/sites\/54\/2024\/11\/colour_04_pc-300x127.jpg 300w, https:\/\/dealer.renault.jp\/renault_kobe\/wp-content\/uploads\/sites\/54\/2024\/11\/colour_04_pc-768x326.jpg 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"blocks-gallery-item__caption\"><strong>\u9650\u5b9a\u30001\u53f0<\/strong><\/figcaption><\/figure><\/li><\/ul><\/figure>\n\n\n\n<p><strong>\u30a8\u30f3\u30b8\u30cb\u30a2\u30fc\u30c9<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-gallery columns-2 is-cropped wp-block-gallery-12 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"589\" height=\"351\" src=\"https:\/\/dealer.renault.jp\/renault_kobe\/wp-content\/uploads\/sites\/54\/2024\/11\/ext_e_tech_03_pc.jpg\" alt=\"\" data-id=\"5191\" data-full-url=\"https:\/\/dealer.renault.jp\/renault_kobe\/wp-content\/uploads\/sites\/54\/2024\/11\/ext_e_tech_03_pc.jpg\" data-link=\"https:\/\/dealer.renault.jp\/renault_kobe\/?attachment_id=5191\" class=\"wp-image-5191\" srcset=\"https:\/\/dealer.renault.jp\/renault_kobe\/wp-content\/uploads\/sites\/54\/2024\/11\/ext_e_tech_03_pc.jpg 589w, https:\/\/dealer.renault.jp\/renault_kobe\/wp-content\/uploads\/sites\/54\/2024\/11\/ext_e_tech_03_pc-300x179.jpg 300w\" sizes=\"auto, (max-width: 589px) 100vw, 589px\" \/><figcaption class=\"blocks-gallery-item__caption\"><strong>\u9650\u5b9a\u30001\u53f0<\/strong><\/figcaption><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"589\" height=\"351\" src=\"https:\/\/dealer.renault.jp\/renault_kobe\/wp-content\/uploads\/sites\/54\/2024\/11\/ext_e_tech_01_pc-1.jpg\" alt=\"\" data-id=\"5190\" data-link=\"https:\/\/dealer.renault.jp\/renault_kobe\/?attachment_id=5190\" class=\"wp-image-5190\" srcset=\"https:\/\/dealer.renault.jp\/renault_kobe\/wp-content\/uploads\/sites\/54\/2024\/11\/ext_e_tech_01_pc-1.jpg 589w, https:\/\/dealer.renault.jp\/renault_kobe\/wp-content\/uploads\/sites\/54\/2024\/11\/ext_e_tech_01_pc-1-300x179.jpg 300w\" sizes=\"auto, (max-width: 589px) 100vw, 589px\" \/><figcaption class=\"blocks-gallery-item__caption\"><strong>\u9650\u5b9a\u30001\u53f0<\/strong><\/figcaption><\/figure><\/li><\/ul><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><strong><span class=\"has-inline-color has-vivid-red-color\">\u30eb\u30ce\u30fc\u795e\u6238\u30aa\u30ea\u30b8\u30ca\u30eb\u7279\u5178\u3067\u3054\u7528\u610f\u3057\u3066\u304a\u308a\u307e\u3059\uff01<\/span><\/strong><\/h2>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>10\u670827\u65e5\u3088\u308a\u62bd\u9078\u7533\u8fbc\u307f\u3092\u958b\u59cb\u3057\u3066\u304a\u308a\u307e\u3059\u300cKANGOO \u9650\u5b9a\u8eca \u30af\u30eb\u30fc\u30ebMT\u300d\u306e\u7533\u8fbc\u7de0\u5207\u304c11\u67089\u65e5\u3068\u8feb\u3063\u3066\u307e\u3044\u308a\u307e\u3057\u305f\u3002\u30c7\u30a3\u30fc\u30bc\u30ebMT\u3068\u8a00\u3046\u3053\u3068\u3082\u3042\u308a\u3054\u5fdc\u52df\u304c\u6bba\u5230\u3057\u3066\u304a\u308a\u307e\u3059\u203c\u307e\u3060\u9593\u306b\u5408\u3044\u307e\u3059\u203c&#8230;<\/p>\n","protected":false},"author":52,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-5171","post","type-post","status-publish","format-standard","hentry","category-info"],"_links":{"self":[{"href":"https:\/\/dealer.renault.jp\/renault_kobe\/wp-json\/wp\/v2\/posts\/5171","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dealer.renault.jp\/renault_kobe\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dealer.renault.jp\/renault_kobe\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dealer.renault.jp\/renault_kobe\/wp-json\/wp\/v2\/users\/52"}],"replies":[{"embeddable":true,"href":"https:\/\/dealer.renault.jp\/renault_kobe\/wp-json\/wp\/v2\/comments?post=5171"}],"version-history":[{"count":4,"href":"https:\/\/dealer.renault.jp\/renault_kobe\/wp-json\/wp\/v2\/posts\/5171\/revisions"}],"predecessor-version":[{"id":5192,"href":"https:\/\/dealer.renault.jp\/renault_kobe\/wp-json\/wp\/v2\/posts\/5171\/revisions\/5192"}],"wp:attachment":[{"href":"https:\/\/dealer.renault.jp\/renault_kobe\/wp-json\/wp\/v2\/media?parent=5171"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dealer.renault.jp\/renault_kobe\/wp-json\/wp\/v2\/categories?post=5171"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dealer.renault.jp\/renault_kobe\/wp-json\/wp\/v2\/tags?post=5171"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}