{"id":5292,"date":"2025-01-20T15:08:20","date_gmt":"2025-01-20T06:08:20","guid":{"rendered":"https:\/\/dealer.renault.jp\/renault_kobe\/?p=5292"},"modified":"2025-01-20T15:08:20","modified_gmt":"2025-01-20T06:08:20","slug":"arkana-special-offer-%e3%81%ae%e3%81%94%e6%a1%88%e5%86%85","status":"publish","type":"post","link":"https:\/\/dealer.renault.jp\/renault_kobe\/info\/arkana-special-offer-%e3%81%ae%e3%81%94%e6%a1%88%e5%86%85","title":{"rendered":"ARKANA SPECIAL OFFER \u306e\u3054\u6848\u5185"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\"><strong>\u4eca\u3001\u4e16\u9593\u3067\u8a71\u984c\u306e\u30af\u30fc\u30daSUV\u3002<\/strong><\/h2>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>\u30eb\u30ce\u30fc  <span class=\"has-inline-color has-luminous-vivid-orange-color\">ARKANA  \u304c\u300cesprit Alpine\u300d<\/span>\u306e\u540d\u3092\u51a0\u3057\u3066\u65b0\u305f\u306bDEBUT\u3057\u307e\u3057\u305f\u3002TVCM\u3067\u3082\u53ea\u4eca\u653e\u6620\u4e2d\u306e\u5927\u4eba\u6c17\u8eca\u3067\u3059\u3002\u305d\u3093\u306a\u300cARKANA\u300d\u306b\u5927\u5909\u304a\u5f97\u306aOFFER\u3092\u3054\u7528\u610f\u3057\u3066\u304a\u308a\u307e\u3059\u3002<\/strong><\/h2>\n\n\n\n<figure class=\"wp-block-gallery columns-1 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"640\" src=\"https:\/\/dealer.renault.jp\/renault_kobe\/wp-content\/uploads\/sites\/54\/2025\/01\/01_main02.jpg\" alt=\"\" data-id=\"5294\" data-full-url=\"https:\/\/dealer.renault.jp\/renault_kobe\/wp-content\/uploads\/sites\/54\/2025\/01\/01_main02.jpg\" data-link=\"https:\/\/dealer.renault.jp\/renault_kobe\/?attachment_id=5294\" class=\"wp-image-5294\" srcset=\"https:\/\/dealer.renault.jp\/renault_kobe\/wp-content\/uploads\/sites\/54\/2025\/01\/01_main02.jpg 1024w, https:\/\/dealer.renault.jp\/renault_kobe\/wp-content\/uploads\/sites\/54\/2025\/01\/01_main02-300x188.jpg 300w, https:\/\/dealer.renault.jp\/renault_kobe\/wp-content\/uploads\/sites\/54\/2025\/01\/01_main02-768x480.jpg 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><\/ul><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>                         \u2015 ARKANA SPECIAL OFFER\u2015<\/strong><\/h2>\n\n\n\n<figure class=\"wp-block-gallery columns-1 is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"200\" src=\"https:\/\/dealer.renault.jp\/renault_kobe\/wp-content\/uploads\/sites\/54\/2025\/01\/04_SPO01.jpg\" alt=\"\" data-id=\"5295\" data-full-url=\"https:\/\/dealer.renault.jp\/renault_kobe\/wp-content\/uploads\/sites\/54\/2025\/01\/04_SPO01.jpg\" data-link=\"https:\/\/dealer.renault.jp\/renault_kobe\/?attachment_id=5295\" class=\"wp-image-5295\" srcset=\"https:\/\/dealer.renault.jp\/renault_kobe\/wp-content\/uploads\/sites\/54\/2025\/01\/04_SPO01.jpg 1024w, https:\/\/dealer.renault.jp\/renault_kobe\/wp-content\/uploads\/sites\/54\/2025\/01\/04_SPO01-300x59.jpg 300w, https:\/\/dealer.renault.jp\/renault_kobe\/wp-content\/uploads\/sites\/54\/2025\/01\/04_SPO01-768x150.jpg 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><\/ul><\/figure>\n\n\n\n<figure class=\"wp-block-gallery columns-1 is-cropped wp-block-gallery-3 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"200\" src=\"https:\/\/dealer.renault.jp\/renault_kobe\/wp-content\/uploads\/sites\/54\/2025\/01\/04_SPO02.jpg\" alt=\"\" data-id=\"5296\" data-full-url=\"https:\/\/dealer.renault.jp\/renault_kobe\/wp-content\/uploads\/sites\/54\/2025\/01\/04_SPO02.jpg\" data-link=\"https:\/\/dealer.renault.jp\/renault_kobe\/?attachment_id=5296\" class=\"wp-image-5296\" srcset=\"https:\/\/dealer.renault.jp\/renault_kobe\/wp-content\/uploads\/sites\/54\/2025\/01\/04_SPO02.jpg 1024w, https:\/\/dealer.renault.jp\/renault_kobe\/wp-content\/uploads\/sites\/54\/2025\/01\/04_SPO02-300x59.jpg 300w, https:\/\/dealer.renault.jp\/renault_kobe\/wp-content\/uploads\/sites\/54\/2025\/01\/04_SPO02-768x150.jpg 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><\/ul><\/figure>\n\n\n\n<figure class=\"wp-block-gallery columns-2 is-cropped wp-block-gallery-4 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"907\" height=\"1024\" src=\"https:\/\/dealer.renault.jp\/renault_kobe\/wp-content\/uploads\/sites\/54\/2025\/01\/03_ARK01-907x1024.jpg\" alt=\"\" data-id=\"5298\" data-link=\"https:\/\/dealer.renault.jp\/renault_kobe\/?attachment_id=5298\" class=\"wp-image-5298\" srcset=\"https:\/\/dealer.renault.jp\/renault_kobe\/wp-content\/uploads\/sites\/54\/2025\/01\/03_ARK01-907x1024.jpg 907w, https:\/\/dealer.renault.jp\/renault_kobe\/wp-content\/uploads\/sites\/54\/2025\/01\/03_ARK01-266x300.jpg 266w, https:\/\/dealer.renault.jp\/renault_kobe\/wp-content\/uploads\/sites\/54\/2025\/01\/03_ARK01-768x867.jpg 768w, https:\/\/dealer.renault.jp\/renault_kobe\/wp-content\/uploads\/sites\/54\/2025\/01\/03_ARK01.jpg 1125w\" sizes=\"auto, (max-width: 907px) 100vw, 907px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"907\" height=\"1024\" src=\"https:\/\/dealer.renault.jp\/renault_kobe\/wp-content\/uploads\/sites\/54\/2025\/01\/03_ARK02-907x1024.jpg\" alt=\"\" data-id=\"5299\" data-full-url=\"https:\/\/dealer.renault.jp\/renault_kobe\/wp-content\/uploads\/sites\/54\/2025\/01\/03_ARK02.jpg\" data-link=\"https:\/\/dealer.renault.jp\/renault_kobe\/?attachment_id=5299\" class=\"wp-image-5299\" srcset=\"https:\/\/dealer.renault.jp\/renault_kobe\/wp-content\/uploads\/sites\/54\/2025\/01\/03_ARK02-907x1024.jpg 907w, https:\/\/dealer.renault.jp\/renault_kobe\/wp-content\/uploads\/sites\/54\/2025\/01\/03_ARK02-266x300.jpg 266w, https:\/\/dealer.renault.jp\/renault_kobe\/wp-content\/uploads\/sites\/54\/2025\/01\/03_ARK02-768x867.jpg 768w, https:\/\/dealer.renault.jp\/renault_kobe\/wp-content\/uploads\/sites\/54\/2025\/01\/03_ARK02.jpg 1125w\" sizes=\"auto, (max-width: 907px) 100vw, 907px\" \/><\/figure><\/li><\/ul><\/figure>\n\n\n\n<figure class=\"wp-block-gallery columns-1 is-cropped wp-block-gallery-5 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"350\" src=\"https:\/\/dealer.renault.jp\/renault_kobe\/wp-content\/uploads\/sites\/54\/2025\/01\/06_arktext05.jpg\" alt=\"\" data-id=\"5300\" data-full-url=\"https:\/\/dealer.renault.jp\/renault_kobe\/wp-content\/uploads\/sites\/54\/2025\/01\/06_arktext05.jpg\" data-link=\"https:\/\/dealer.renault.jp\/renault_kobe\/?attachment_id=5300\" class=\"wp-image-5300\" srcset=\"https:\/\/dealer.renault.jp\/renault_kobe\/wp-content\/uploads\/sites\/54\/2025\/01\/06_arktext05.jpg 1024w, https:\/\/dealer.renault.jp\/renault_kobe\/wp-content\/uploads\/sites\/54\/2025\/01\/06_arktext05-300x103.jpg 300w, https:\/\/dealer.renault.jp\/renault_kobe\/wp-content\/uploads\/sites\/54\/2025\/01\/06_arktext05-768x263.jpg 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><\/ul><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>\u4eca\u3001\u4e16\u9593\u3067\u8a71\u984c\u306e\u30af\u30fc\u30daSUV\u3002 \u30eb\u30ce\u30fc ARKANA \u304c\u300cesprit Alpine\u300d\u306e\u540d\u3092\u51a0\u3057\u3066\u65b0\u305f\u306bDEBUT\u3057\u307e\u3057\u305f\u3002TVCM\u3067\u3082\u53ea\u4eca\u653e\u6620\u4e2d\u306e\u5927\u4eba\u6c17\u8eca\u3067\u3059\u3002\u305d\u3093\u306a\u300cARKANA\u300d\u306b\u5927\u5909\u304a\u5f97\u306aOF&#8230;<\/p>\n","protected":false},"author":52,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-5292","post","type-post","status-publish","format-standard","hentry","category-info"],"_links":{"self":[{"href":"https:\/\/dealer.renault.jp\/renault_kobe\/wp-json\/wp\/v2\/posts\/5292","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dealer.renault.jp\/renault_kobe\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dealer.renault.jp\/renault_kobe\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dealer.renault.jp\/renault_kobe\/wp-json\/wp\/v2\/users\/52"}],"replies":[{"embeddable":true,"href":"https:\/\/dealer.renault.jp\/renault_kobe\/wp-json\/wp\/v2\/comments?post=5292"}],"version-history":[{"count":4,"href":"https:\/\/dealer.renault.jp\/renault_kobe\/wp-json\/wp\/v2\/posts\/5292\/revisions"}],"predecessor-version":[{"id":5303,"href":"https:\/\/dealer.renault.jp\/renault_kobe\/wp-json\/wp\/v2\/posts\/5292\/revisions\/5303"}],"wp:attachment":[{"href":"https:\/\/dealer.renault.jp\/renault_kobe\/wp-json\/wp\/v2\/media?parent=5292"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dealer.renault.jp\/renault_kobe\/wp-json\/wp\/v2\/categories?post=5292"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dealer.renault.jp\/renault_kobe\/wp-json\/wp\/v2\/tags?post=5292"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}