{"id":2028,"date":"2013-05-21T20:20:46","date_gmt":"2013-05-21T11:20:46","guid":{"rendered":"https:\/\/dealer.renault.jp\/renault_nextonetokushima\/?p=2028"},"modified":"2013-05-21T20:20:46","modified_gmt":"2013-05-21T11:20:46","slug":"%e2%98%85%e3%80%80rj%e3%82%a2%e3%83%af%e3%83%bc%e3%83%89%e3%80%80%e2%98%85","status":"publish","type":"post","link":"https:\/\/dealer.renault.jp\/renault_tokushima\/diary\/%e2%98%85%e3%80%80rj%e3%82%a2%e3%83%af%e3%83%bc%e3%83%89%e3%80%80%e2%98%85","title":{"rendered":"\u2605\u3000RJ\u30a2\u30ef\u30fc\u30c9\u3000\u2605"},"content":{"rendered":"<p>\u307c\u3093\u305d\u308f\uff5e\u2606<\/p>\n<p>\uff15\u6708\uff12\uff10\u65e5\u306b\u884c\u308f\u308c\u307e\u3057\u305f\u3000\u3010\u3000\u30eb\u30ce\u30fc\u7dcf\u4f1a\u3000\u3011\u3000\u3068<\/p>\n<p>\u2605\u3000\u30eb\u30ce\u30fc\u30fb\u30b8\u30e3\u30dd\u30f3\u30a2\u30ef\u30fc\u30c9\uff12\uff10\uff11\uff12\u3000\u2605\u3000\u3078\u51fa\u639b\u3051\u3066\u304a\u308a\u307e\u3057\u305f\uff01\uff01<\/p>\n<p><a rel=\"attachment wp-att-7741\" href=\"https:\/\/dealer.renault.jp\/renault_nextonetokushima\/?attachment_id=7741\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/nextone.biz\/wp\/wp-content\/uploads\/2013\/05\/130521y2.jpg\" alt=\"130521y2\" width=\"550\" height=\"412\" \/><\/a><\/p>\n<p>\u3046\u305a\u3074\u30fc\u3061\u3083\u3093\u3001\u53ef\u611b\u3044\uff5e\u2764<\/p>\n<p><a rel=\"attachment wp-att-7740\" href=\"https:\/\/dealer.renault.jp\/renault_nextonetokushima\/?attachment_id=7740\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/nextone.biz\/wp\/wp-content\/uploads\/2013\/05\/130521y.jpg\" alt=\"130521y\" width=\"550\" height=\"412\" \/><\/a><\/p>\n<p>\u300c\u3000\u3042\u308b\u3067\u3088\u5fb3\u5cf6\u3000\u300d\u3000\u3063\u3066\u8a00\u8449\u3001\u597d\u304d\u3067\u3059\u2606<\/p>\n<p>\u5fb3\u5cf6\u963f\u6ce2\u304a\u3069\u308a\u7a7a\u6e2f\u3000\u21d2\u3000\u7fbd\u7530\u7a7a\u6e2f\u3000\u3078\uff08\uff1e\u2200\uff1c\uff42\uff09\uff42\u3000\u98db\u3093\u3067\u884c\u304d\u307e\u3059\u266a<\/p>\n<p>\u7fbd\u7530\u7a7a\u6e2f\u3067\u306f\u3001<\/p>\n<p><a rel=\"attachment wp-att-7742\" href=\"https:\/\/dealer.renault.jp\/renault_nextonetokushima\/?attachment_id=7742\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/nextone.biz\/wp\/wp-content\/uploads\/2013\/05\/130521y3.jpg\" alt=\"130521y3\" width=\"495\" height=\"403\" \/><\/a><\/p>\n<p>\u6771\u4eac\u30aa\u30ea\u30f3\u30d4\u30c3\u30af\uff12\uff10\uff12\uff10\u958b\u50ac\u3092\u5fdc\u63f4\u3059\u308b\u611b\u3061\u3083\u3093\u306b\u906d\u9047\u3057\u307e\u3057\u305f\uff50\uff08\uff1e\u2200\uff1c\uff51\uff09<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u307c\u3093\u305d\u308f\uff5e\u2606 \uff15\u6708\uff12\uff10\u65e5\u306b\u884c\u308f\u308c\u307e\u3057\u305f\u3000\u3010\u3000\u30eb\u30ce\u30fc\u7dcf\u4f1a\u3000\u3011\u3000\u3068 \u2605\u3000\u30eb\u30ce\u30fc\u30fb\u30b8\u30e3\u30dd\u30f3\u30a2\u30ef\u30fc\u30c9\uff12\uff10\uff11\uff12\u3000\u2605\u3000\u3078\u51fa\u639b\u3051\u3066\u304a\u308a\u307e\u3057\u305f\uff01\uff01 \u3046\u305a\u3074\u30fc\u3061\u3083\u3093\u3001\u53ef\u611b\u3044\uff5e\u2764 \u300c\u3000\u3042\u308b\u3067\u3088\u5fb3\u5cf6\u3000\u300d\u3000\u3063\u3066\u8a00\u8449\u3001\u597d\u304d\u3067\u3059&#8230;<\/p>\n","protected":false},"author":62,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-2028","post","type-post","status-publish","format-standard","hentry","category-diary"],"_links":{"self":[{"href":"https:\/\/dealer.renault.jp\/renault_tokushima\/wp-json\/wp\/v2\/posts\/2028","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dealer.renault.jp\/renault_tokushima\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dealer.renault.jp\/renault_tokushima\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dealer.renault.jp\/renault_tokushima\/wp-json\/wp\/v2\/users\/62"}],"replies":[{"embeddable":true,"href":"https:\/\/dealer.renault.jp\/renault_tokushima\/wp-json\/wp\/v2\/comments?post=2028"}],"version-history":[{"count":0,"href":"https:\/\/dealer.renault.jp\/renault_tokushima\/wp-json\/wp\/v2\/posts\/2028\/revisions"}],"wp:attachment":[{"href":"https:\/\/dealer.renault.jp\/renault_tokushima\/wp-json\/wp\/v2\/media?parent=2028"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dealer.renault.jp\/renault_tokushima\/wp-json\/wp\/v2\/categories?post=2028"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dealer.renault.jp\/renault_tokushima\/wp-json\/wp\/v2\/tags?post=2028"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}